{"id":8398,"date":"2015-10-02T15:49:02","date_gmt":"2015-10-02T15:49:02","guid":{"rendered":"http:\/\/c0290214.ferozo.com\/wpnews\/?p=8398"},"modified":"2015-10-02T15:49:02","modified_gmt":"2015-10-02T15:49:02","slug":"clia-confirma-que-la-industria-del-cuero-china-sigue-creciendo","status":"publish","type":"post","link":"http:\/\/cueroamerica.info\/wpnews\/2015\/10\/clia-confirma-que-la-industria-del-cuero-china-sigue-creciendo\/","title":{"rendered":"CLIA confirma que la industria del cuero china sigue creciendo"},"content":{"rendered":"<div id=\"attachment_8396\" style=\"width: 133px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/c0290214.ferozo.com\/wpnews\/wp-content\/uploads\/2015\/10\/Su-Chao-Ying.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8396\" class=\" wp-image-8396\" src=\"http:\/\/c0290214.ferozo.com\/wpnews\/wp-content\/uploads\/2015\/10\/Su-Chao-Ying-205x300.jpg\" alt=\"Su Chao Ying\" width=\"123\" height=\"180\" srcset=\"http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Su-Chao-Ying-205x300.jpg 205w, http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Su-Chao-Ying-768x1124.jpg 768w, http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Su-Chao-Ying-699x1024.jpg 699w, http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Su-Chao-Ying.jpg 963w\" sizes=\"auto, (max-width: 123px) 100vw, 123px\" \/><\/a><p id=\"caption-attachment-8396\" class=\"wp-caption-text\">Su Chao Ying<\/p><\/div>\n<p>Durante la All China Leather Exhibition (ACLE 2015), Su Chao Ying, presidente de la Asociaci\u00f3n de la Industria del Cuero de China (CLIA), inform\u00f3 en conferencia de prensa la situaci\u00f3n actual del sector. Destac\u00f3 que se registr\u00f3 un crecimiento del 6% y que este ritmo se mantendr\u00e1 en ascenso.<\/p>\n<p>Su Chao Ying dijo que despu\u00e9s de<\/p>\n<p>30 a\u00f1os de fuerte y continuo crecimiento, bien se pod\u00eda esperar una desaceleraci\u00f3n y que, por lo tanto, mantenerse en este nivel ser\u00eda un buen resultado.<\/p>\n<p>El dirigente chino detall\u00f3 que la exportaci\u00f3n de calzado cay\u00f3 levemente en 2014 y que la importaci\u00f3n subi\u00f3 un 32% en volumen, al alcanzar los 46 millones de pares. Este aumento fue del 20% en valor, al sumar US$ 1.100 millones. Para Su Chao Ying, estas cifras muestran que la producci\u00f3n local no puede satisfacer la creciente demanda de los consumidores chinos.<\/p>\n<div id=\"attachment_8397\" style=\"width: 119px\" class=\"wp-caption alignright\"><a href=\"http:\/\/c0290214.ferozo.com\/wpnews\/wp-content\/uploads\/2015\/10\/Michael-Duck_3.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8397\" class=\" wp-image-8397\" src=\"http:\/\/c0290214.ferozo.com\/wpnews\/wp-content\/uploads\/2015\/10\/Michael-Duck_3-225x300.jpg\" alt=\"Michael Duck\" width=\"109\" height=\"145\" srcset=\"http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Michael-Duck_3-225x300.jpg 225w, http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Michael-Duck_3-767x1024.jpg 767w, http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Michael-Duck_3-112x150.jpg 112w, http:\/\/cueroamerica.info\/wpnews\/wp-content\/uploads\/2015\/10\/Michael-Duck_3.jpg 1806w\" sizes=\"auto, (max-width: 109px) 100vw, 109px\" \/><\/a><p id=\"caption-attachment-8397\" class=\"wp-caption-text\">Michael Duck<\/p><\/div>\n<p>Tambi\u00e9n, anunci\u00f3 que la industria tratar\u00e1 de mejorar los costos mediante un mayor grado de automatizaci\u00f3n en los sectores cuero y calzado. Modernizar el dise\u00f1o del calzado chino tambi\u00e9n ser\u00eda una prioridad a ser estudiada.<\/p>\n<p>Al cerrar la conferencia Michael Duck, director de APLF, se\u00f1al\u00f3 que \u00abpodemos discutir los n\u00fameros del crecimiento, pero China continuara creciendo y la industria del cuero local tambi\u00e9n\u201d.<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>\nFashionNetAsia \/ CueroAm\u00e9rica<\/p>\n<p dir=\"ltr\">\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014<\/p>\n<p dir=\"ltr\">Para comunicarse con CueroAm\u00e9rica: <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"mailto:contacto@cueroamerica.com\">contacto@cueroamerica.com<\/a><\/span><\/p>\n<table border=\"0\" width=\"460\">\n<tbody>\n<tr>\n<td width=\"300\"><a href=\"http:\/\/www.aplf.com\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cueroamerica.com.ar\/img\/aplf-fa-mmt.gif\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<td width=\"171\"><a href=\"http:\/\/www.cueroamerica.com.ar\/sponsors\/dfsudamericana\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cueroamerica.com.ar\/sponsors\/dfsudbanner_300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" border=\"0\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Durante la All China Leather Exhibition (ACLE 2015), Su Chao Ying, presidente de la Asociaci\u00f3n de la Industria del Cuero de China (CLIA), inform\u00f3 en conferencia de prensa la situaci\u00f3n actual del sector. Destac\u00f3 que se registr\u00f3 un crecimiento del 6% y que este ritmo se mantendr\u00e1 en ascenso. Su Chao Ying dijo que despu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,62],"tags":[],"class_list":["post-8398","post","type-post","status-publish","format-standard","hentry","category-mercados","category-noticias-de-asia","count-0","even alt","author-","last"],"_links":{"self":[{"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/posts\/8398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/comments?post=8398"}],"version-history":[{"count":3,"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/posts\/8398\/revisions"}],"predecessor-version":[{"id":8401,"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/posts\/8398\/revisions\/8401"}],"wp:attachment":[{"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/media?parent=8398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/categories?post=8398"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cueroamerica.info\/wpnews\/wp-json\/wp\/v2\/tags?post=8398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}